﻿{"id":7939,"date":"2007-10-06T14:47:03","date_gmt":"2007-10-06T11:47:03","guid":{"rendered":"https:\/\/www.iceht.forth.gr\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/"},"modified":"2022-12-08T12:31:44","modified_gmt":"2022-12-08T10:31:44","slug":"unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands","status":"publish","type":"publications","link":"https:\/\/www.iceht.forth.gr\/en\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/","title":{"rendered":"Unsymmetrical single-component nickel 1-2-dithiolene complexes with extended tetrachalcogenafulvalenedithiolato ligands"},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"tags":[37],"class_list":["post-7939","publications","type-publications","status-publish","hentry","tag-nanotechnology-advanced-materials-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsymmetrical single-component nickel 1-2-dithiolene complexes with extended tetrachalcogenafulvalenedithiolato ligands - FORTH \/ ICE-HT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iceht.forth.gr\/en\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsymmetrical single-component nickel 1-2-dithiolene complexes with extended tetrachalcogenafulvalenedithiolato ligands - FORTH \/ ICE-HT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iceht.forth.gr\/en\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/\" \/>\n<meta property=\"og:site_name\" content=\"FORTH \/ ICE-HT\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-08T10:31:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/publications\\\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\\\/\",\"url\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/publications\\\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\\\/\",\"name\":\"Unsymmetrical single-component nickel 1-2-dithiolene complexes with extended tetrachalcogenafulvalenedithiolato ligands - FORTH \\\/ ICE-HT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/#website\"},\"datePublished\":\"2007-10-06T11:47:03+00:00\",\"dateModified\":\"2022-12-08T10:31:44+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/publications\\\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/\",\"name\":\"FORTH \\\/ ICE-HT\",\"description\":\"\u0399\u03a4\u0395\\\/\u0399\u0395\u03a7\u039c\u0397\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/#organization\",\"name\":\"FORTH \\\/ ICE-HT\",\"url\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iceht.forth.gr\\\/wp-content\\\/uploads\\\/Forth-en-transparent-disc-inside.png\",\"contentUrl\":\"https:\\\/\\\/www.iceht.forth.gr\\\/wp-content\\\/uploads\\\/Forth-en-transparent-disc-inside.png\",\"width\":995,\"height\":228,\"caption\":\"FORTH \\\/ ICE-HT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iceht.forth.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsymmetrical single-component nickel 1-2-dithiolene complexes with extended tetrachalcogenafulvalenedithiolato ligands - FORTH \/ ICE-HT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iceht.forth.gr\/en\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/","og_locale":"en_US","og_type":"article","og_title":"Unsymmetrical single-component nickel 1-2-dithiolene complexes with extended tetrachalcogenafulvalenedithiolato ligands - FORTH \/ ICE-HT","og_url":"https:\/\/www.iceht.forth.gr\/en\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/","og_site_name":"FORTH \/ ICE-HT","article_modified_time":"2022-12-08T10:31:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iceht.forth.gr\/en\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/","url":"https:\/\/www.iceht.forth.gr\/en\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/","name":"Unsymmetrical single-component nickel 1-2-dithiolene complexes with extended tetrachalcogenafulvalenedithiolato ligands - FORTH \/ ICE-HT","isPartOf":{"@id":"https:\/\/www.iceht.forth.gr\/en\/#website"},"datePublished":"2007-10-06T11:47:03+00:00","dateModified":"2022-12-08T10:31:44+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iceht.forth.gr\/en\/publications\/unsymmetrical-single-component-nickel-1-2-dithiolene-complexes-with-extended-tetrachalcogenafulvalenedithiolato-ligands\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.iceht.forth.gr\/en\/#website","url":"https:\/\/www.iceht.forth.gr\/en\/","name":"FORTH \/ ICE-HT","description":"\u0399\u03a4\u0395\/\u0399\u0395\u03a7\u039c\u0397","publisher":{"@id":"https:\/\/www.iceht.forth.gr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iceht.forth.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.iceht.forth.gr\/en\/#organization","name":"FORTH \/ ICE-HT","url":"https:\/\/www.iceht.forth.gr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.iceht.forth.gr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.iceht.forth.gr\/wp-content\/uploads\/Forth-en-transparent-disc-inside.png","contentUrl":"https:\/\/www.iceht.forth.gr\/wp-content\/uploads\/Forth-en-transparent-disc-inside.png","width":995,"height":228,"caption":"FORTH \/ ICE-HT"},"image":{"@id":"https:\/\/www.iceht.forth.gr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.iceht.forth.gr\/en\/wp-json\/wp\/v2\/publications\/7939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iceht.forth.gr\/en\/wp-json\/wp\/v2\/publications"}],"about":[{"href":"https:\/\/www.iceht.forth.gr\/en\/wp-json\/wp\/v2\/types\/publications"}],"wp:attachment":[{"href":"https:\/\/www.iceht.forth.gr\/en\/wp-json\/wp\/v2\/media?parent=7939"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iceht.forth.gr\/en\/wp-json\/wp\/v2\/tags?post=7939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}